{"id":80588,"date":"2024-03-21T16:56:37","date_gmt":"2024-03-21T20:56:37","guid":{"rendered":"https:\/\/www.ludwig-van.com\/montreal\/?p=80588"},"modified":"2024-03-21T17:25:12","modified_gmt":"2024-03-21T21:25:12","slug":"critique-le-cas-makela-ou-du-danger-de-consacrer-nos-heros-trop-tot","status":"publish","type":"post","link":"https:\/\/www.ludwig-van.com\/montreal\/2024\/03\/21\/critique-le-cas-makela-ou-du-danger-de-consacrer-nos-heros-trop-tot\/","title":{"rendered":"CRITIQUE | Le cas M\u00e4kel\u00e4, ou Du danger de consacrer nos h\u00e9ros trop t\u00f4t"},"content":{"rendered":"<figure id=\"attachment_80625\" aria-describedby=\"caption-attachment-80625\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-80625\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_par-Mathias_Benguigui.jpg\" alt=\"Klaus M\u00e4kel\u00e4 et l'Orchestre de Paris \u00e0 la Maison symphonique le 19 mars 2024. (Photo : Mathias Benguigui)\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_par-Mathias_Benguigui.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_par-Mathias_Benguigui-300x200.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_par-Mathias_Benguigui-1024x683.jpg 1024w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_par-Mathias_Benguigui-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-80625\" class=\"wp-caption-text\">Klaus M\u00e4kel\u00e4 et l&rsquo;Orchestre de Paris \u00e0 la Maison symphonique le 19 mars 2024. (Photo : Mathias Benguigui)<\/figcaption><\/figure>\n<p>Le concert tant attendu de l&rsquo;<strong>Orchestre de Paris<\/strong> et de son chef attitr\u00e9 <strong>Klaus M\u00e4kel\u00e4<\/strong> a eu lieu mardi soir dernier \u00e0 la <strong>Maison symphonique.<\/strong> Avant Montr\u00e9al, l&rsquo;ensemble s&rsquo;\u00e9tait arr\u00eat\u00e9 \u00e0 Ann Arbor, New York et Boston. Partout sauf \u00e0 New York, il a jou\u00e9 son programme de Debussy, Stravinsky et Rachmaninov avec le soliste <strong>Yunchan Lim<\/strong>. Le concert au <strong>Carnegie Hall<\/strong> de New York, capt\u00e9 pour la cha\u00eene sp\u00e9cialis\u00e9e medici.tv, laissait tomber Debussy et Rachmaninov en faveur d&rsquo;un programme 100 % Stravinsky, soit l&rsquo;<em>Oiseau de feu<\/em> maintenu du premier programme, auquel venait se greffer le <em>Sacre du printemps<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_80623\" aria-describedby=\"caption-attachment-80623\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-80623\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Orchestre-de-Paris_-Yunchan-Lim_Klaus-Makela_-credit-Mathias_Benguigui.jpg\" alt=\"Le soliste acclam\u00e9 Yunchan Lim au piano, accompagn\u00e9 par l'Orchestre de Paris sous la direction de Klaus M\u00e4kel\u00e4. (Photo : Mathias Benguigui)\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Orchestre-de-Paris_-Yunchan-Lim_Klaus-Makela_-credit-Mathias_Benguigui.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Orchestre-de-Paris_-Yunchan-Lim_Klaus-Makela_-credit-Mathias_Benguigui-300x200.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Orchestre-de-Paris_-Yunchan-Lim_Klaus-Makela_-credit-Mathias_Benguigui-1024x683.jpg 1024w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Orchestre-de-Paris_-Yunchan-Lim_Klaus-Makela_-credit-Mathias_Benguigui-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-80623\" class=\"wp-caption-text\">Le soliste acclam\u00e9 Yunchan Lim au piano, accompagn\u00e9 par l&rsquo;Orchestre de Paris sous la direction de Klaus M\u00e4kel\u00e4. (Photo : Mathias Benguigui)<\/figcaption><\/figure>\n<h3>Le soliste<\/h3>\n<p>Une grande partie de l&rsquo;assistance s&rsquo;\u00e9tait d\u00e9plac\u00e9e pour entendre <strong>Yunchan Lim<\/strong>, le plus jeune laur\u00e9at du concours international Van Cliburn. Le pianiste d&rsquo;origine cor\u00e9enne a pu mettre son impressionnante virtuosit\u00e9 en valeur dans le Concerto pour piano no 2 de Rachmaninov. Son timbre \u00e9pur\u00e9 et concentr\u00e9 se jumelait bien au timbre de l&rsquo;Orchestre de Paris, lui aussi plus incisif qu&rsquo;expansif &#8211; un mariage de sonorit\u00e9 portant un peu \u00e0 regretter qu&rsquo;ils n&rsquo;aient pas interpr\u00e9ter le Concerto pour piano no 2 de Prokofiev, annonc\u00e9 \u00e0 l&rsquo;origine. Lim privil\u00e9gie une articulation d\u00e9taill\u00e9e, ne laissant la p\u00e9dale rien embrouiller, et une structure ferme. Malgr\u00e9 qu&rsquo;il aurait pu laisser respirer certaines phrases, cela a pour avantage qu&rsquo;il ne perd jamais de vue les grandes lignes. Les m\u00eames qualit\u00e9s et inconv\u00e9nients ont transparu dans l&rsquo;\u00c9tude op. 10 no 3 de Chopin jou\u00e9e en rappel, les couleurs tendres et touchantes qu&rsquo;il \u00e9licitait voulant vivre l\u00e9g\u00e8rement au-del\u00e0 du temps qu&rsquo;il leur accordait.<\/p>\n<h3>L&rsquo;orchestre et le chef<\/h3>\n<p>Klaus M\u00e4kel\u00e4 laisse beaucoup de libert\u00e9 aux instrumentistes qu&rsquo;il dirige, ce qui contribue \u00e0 le faire aimer de ceux-ci. C&rsquo;est une approche consciente, qui lui a \u00e9t\u00e9 impartie par son professeur <strong>Jorma Panula<\/strong>, le grand ma\u00eetre de la direction d&rsquo;orchestre en Finlande et \u00e0 travers le monde. L&rsquo;ancien disciple l&rsquo;applique \u00e0 l&rsquo;extr\u00eame, abandonnant souvent compl\u00e8tement les gestes de direction. Avec les remarquables musicien.ne.s de l&rsquo;Orchestre de Paris, cela donne d&rsquo;excellents r\u00e9sultats dans les solos : celui de la premi\u00e8re fl\u00fbte dans le <em>Pr\u00e9lude \u00e0 l&rsquo;apr\u00e8s-midi d&rsquo;un faune<\/em>, limpide et langoureux, mais \u00e9galement ceux, tout aussi sublimes, du premier hautbois, du premier cor et du premier basson dans les autres oeuvres.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_80624\" aria-describedby=\"caption-attachment-80624\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-80624\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_-par-Mathias_Benguigui.jpg\" alt=\"Klaus M\u00e4kel\u00e4 dans un moment d'int\u00e9riorit\u00e9 avec l'Orchestre de Paris. (Photo : Mathias Benguigui)\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_-par-Mathias_Benguigui.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_-par-Mathias_Benguigui-300x200.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_-par-Mathias_Benguigui-1024x683.jpg 1024w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Klaus-Makela-et-lOrchestre-de-Paris_-par-Mathias_Benguigui-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-80624\" class=\"wp-caption-text\">Klaus M\u00e4kel\u00e4 dans un moment d&rsquo;int\u00e9riorit\u00e9 avec l&rsquo;Orchestre de Paris. (Photo : Mathias Benguigui)<\/figcaption><\/figure>\n<p>Et quand surviennent des ponctuations rythmiques, M\u00e4kel\u00e4 prend l&rsquo;orchestre en main, soulevant le bras avec \u00e9nergie et le rabattant avec assurance pour faire \u00e9merger des accords incisifs, color\u00e9s de juste ce qu&rsquo;il faut de timbre cuivr\u00e9 de la part des trombones. Le son de l&rsquo;orchestre s&rsquo;en trouve soudainement plus compact, plus percutant. Les crescendos sont \u00e9galement parfaitement dos\u00e9s, comme si M\u00e4kel\u00e4 tournait progressivement un bouton de volume contr\u00f4lant tout l&rsquo;orchestre.<\/p>\n<p>Les passages probl\u00e9matiques surviennent entre ces deux extr\u00eames. Makel\u00e4 dit lui-m\u00eame en entrevue qu&rsquo;\u00e9videmment, pour pouvoir laisser autant de libert\u00e9, il faut aussi savoir intervenir au bon moment &#8211; mais \u00e0 entendre de nombreuses entr\u00e9es de groupe peu soign\u00e9es chez les bois et des passages au flou rythmique inattendu, il semble que ses crit\u00e8res pour d\u00e9terminer ces bons moments ne soient pas les m\u00eames que les miens. M\u00eame en admettant que ces faiblesses aient \u00e9t\u00e9 caus\u00e9es par la fatigue de fin de tourn\u00e9e, le chef devrait y r\u00e9agir et intervenir imm\u00e9diatement pour offrir aux instrumentistes le guide dont ils ont besoin pour donner le meilleur d&rsquo;eux-m\u00eames \u00e0 ce moment pr\u00e9cis.<\/p>\n<p>Bref, je dois avouer que je suis sortie plus perplexe qu&rsquo;enthousiaste du concert. Peut-\u00eatre qu&rsquo;\u00e9couter le documentaire <em>Klaus M\u00e4kel\u00e4 : Vers la flamme<\/em>, r\u00e9alis\u00e9 par <strong>Bruno<\/strong> <strong>Monsaingeon<\/strong>, n&rsquo;\u00e9tait pas la bonne fa\u00e7on de m&rsquo;y pr\u00e9parer. L&rsquo;affirmation du r\u00e9alisateur comme quoi il consid\u00e8re Klaus M\u00e4kel\u00e4 \u00ab\u00a0tout simplement comme le plus grand chef d&rsquo;orchestre du XXIe si\u00e8cle\u00a0\u00bb ne peut \u00eatre que de l&rsquo;hyperbole (mis \u00e0 part le concept absurde de pouvoir d\u00e9terminer LE meilleur chef, il reste quand m\u00eame plus que les trois-quarts du XXIe si\u00e8cle devant nous) &#8211; mais je ne peux nier qu&rsquo;elle a contribu\u00e9 \u00e0 hausser mes attentes. Apr\u00e8s tout, le jeune Finlandais a \u00e9t\u00e9 nomm\u00e9 \u00e0 la t\u00eate de l&rsquo;Orchestre philharmonique d&rsquo;Oslo \u00e0 22 ans, a pris la direction de celui de Paris \u00e0 25 ans, et n&rsquo;aura que 31 ans quand il deviendra le directeur musical de l&rsquo;Orchestre du Concertgebouw en 2027 (il est pour l&rsquo;instant \u00ab\u00a0partenaire officiel\u00a0\u00bb de l&rsquo;orchestre). Comment ne pas s&rsquo;attendre \u00e0 de grandes choses?<\/p>\n<p>Ces attentes ont-elles \u00e9t\u00e9 satisfaites? Pas tout \u00e0 fait.<\/p>\n<h2><em>Inscrivez-vous \u00e0 notre infolettre! La musique classique et l\u2019op\u00e9ra en 5 minutes, chaque jour<\/em>\u00a0\u00a0<a href=\"https:\/\/ludwig-van.us9.list-manage.com\/subscribe?u=4f785cb3f9058f2393ccad035&amp;id=b9b160c032\" target=\"_blank\" rel=\"noopener noreferrer\">ICI\u00a0<\/a><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le concert tant attendu de l&rsquo;Orchestre de Paris et de son chef attitr\u00e9 Klaus M\u00e4kel\u00e4 a eu lieu mardi soir dernier \u00e0 la Maison symphonique. Avant Montr\u00e9al, l&rsquo;ensemble s&rsquo;\u00e9tait arr\u00eat\u00e9 \u00e0 Ann Arbor, New York et Boston. <\/p>\n","protected":false},"author":55,"featured_media":80626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false},"categories":[42107,52],"tags":[42106,2520],"yst_prominent_words":[9906,13122,33388,9813,9869,7059,12692,7560,10056,12688,9841],"acf":[],"jetpack_featured_media_url":"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2024\/03\/Copie-de-CRITIQUE7.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bdYt-kXO","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/80588"}],"collection":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/comments?post=80588"}],"version-history":[{"count":5,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/80588\/revisions"}],"predecessor-version":[{"id":80630,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/80588\/revisions\/80630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media\/80626"}],"wp:attachment":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media?parent=80588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/categories?post=80588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/tags?post=80588"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/yst_prominent_words?post=80588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}