{"id":75081,"date":"2023-02-04T10:07:07","date_gmt":"2023-02-04T15:07:07","guid":{"rendered":"https:\/\/www.ludwig-van.com\/montreal\/?p=75081"},"modified":"2023-02-04T10:25:31","modified_gmt":"2023-02-04T15:25:31","slug":"rencontre-david-bontemps-compositeur-flambeau-fiction-haitienne-opera","status":"publish","type":"post","link":"https:\/\/www.ludwig-van.com\/montreal\/2023\/02\/04\/rencontre-david-bontemps-compositeur-flambeau-fiction-haitienne-opera\/","title":{"rendered":"RENCONTRE | David Bontemps, compositeur: La Flambeau, une fiction ha\u00eftienne \u00e0 l&rsquo;op\u00e9ra"},"content":{"rendered":"<figure id=\"attachment_75089\" aria-describedby=\"caption-attachment-75089\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-75089\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2023\/02\/David-Bontemps-cr-Kevin-Calixte.jpg\" alt=\"David Bontemps, compositeur montr\u00e9alais d'origine ha\u00eftienne. (Photo: Kevin Calixte)\" width=\"1200\" height=\"628\" \/><figcaption id=\"caption-attachment-75089\" class=\"wp-caption-text\">David Bontemps, compositeur montr\u00e9alais d&rsquo;origine ha\u00eftienne. (Photo: Kevin Calixte)<\/figcaption><\/figure>\n<h3><span style=\"color: #808080;\">Dans le cadre du Mois de l\u2019histoire des Noirs, l\u2019Orchestre classique de Montr\u00e9al pr\u00e9sente cette semaine en premi\u00e8re mondiale l\u2019op\u00e9ra La Flambeau, de David Bontemps, sur un livret de Faubert Bolivar. Entretien avec le compositeur montr\u00e9alais d\u2019origine ha\u00eftienne, qui nous parle de sa cr\u00e9ation.<\/span><\/h3>\n<p><strong>LVM\u00a0: Pouvez-vous nous parler de vous et d\u00e9crire votre parcours?<\/strong><\/p>\n<p><strong>David Bontemps\u00a0:<\/strong> \u00ab\u00a0J\u2019ai grandi en Ha\u00efti, \u00e0 Port-au-Prince, o\u00f9 j\u2019ai suivi des cours priv\u00e9s de piano pendant dix ans, avec Serge Villedrouin, lui-m\u00eame pianiste et compositeur. J\u2019ai peu \u00e0 peu \u00e9t\u00e9 mis en contact avec les compositeurs classiques europ\u00e9ens, et aussi, avec les compositeurs classiques ha\u00eftiens. C\u2019est en apprenant les pi\u00e8ces de cette \u00e9cole nationale de composition que je suis moi-m\u00eame devenu int\u00e9ress\u00e9 \u00e0 composer de cette fa\u00e7on, \u00e0 savoir comment styliser les traditions musicales du pays. D\u2019autre part, je suis arriv\u00e9 au Qu\u00e9bec en 2002 pour mes \u00e9tudes en droit. Je ne suis pas devenu avocat, car j\u2019ai choisi de me tourner vers la musique.\u00a0\u00bb<\/p>\n<p><strong>LVM : Existe-t-il des compositeurs ha\u00eftiens connus en musique classique?<\/strong><\/p>\n<p><strong>David Bontemps\u00a0<\/strong>: \u00ab\u00a0Qui ont d\u00e9pass\u00e9 le cadre culturel ha\u00eftien? \u00c7a commence. Il y a Ludovic Lamothe et Justin Elie, par exemple. Ce sont des compositeurs qui sont d\u00e9c\u00e9d\u00e9s et on en d\u00e9couvre qui ont v\u00e9cu dans les ann\u00e9es 1800, mais ils ne sont pas forc\u00e9ment connus, m\u00eame du public ha\u00eftien. On commence \u00e0 les faire conna\u00eetre et \u00e0 les faire sortir du cercle des connaisseurs. On peut donner, \u00e0 titre d\u2019exemple, l\u2019album <em>Ha\u00efti mon amour<\/em>, de la pianiste <strong>C\u00e9lim\u00e8ne Daudet<\/strong>, une franco-ha\u00eftienne, et qui pr\u00e9sente des pi\u00e8ces de compositeurs ha\u00eftiens. \u00bb<\/p>\n<p><strong>LVM\u00a0: Autrement, \u00e0 quoi ressemble la musique ha\u00eftienne?<\/strong><\/p>\n<p><strong>David Bontemps<\/strong>\u00a0: \u00ab\u00a0Il y en a de toutes sortes, bien s\u00fbr les musiques traditionnelles, c\u2019est-\u00e0-dire celles que les esclaves ont emport\u00e9es avec eux et qui sont g\u00e9n\u00e9ralement conserv\u00e9es dans la tradition vaudou. Que ce soit de la musique sacr\u00e9e ou profane, c\u2019est de la musique d\u2019essence africaine. Il y a aussi la musique urbaine, populaire, dansante, dont on conna\u00eet maintenant le compas et le merengue. Il y a \u00e9galement les musiques plus savantes, dont le classique et le jazz, qui s\u2019inspire autant des musiques urbaines et de type folklorique.<\/p>\n<p><strong>LVM\u00a0: Dans votre op\u00e9ra, avez-vous int\u00e9gr\u00e9 ces diff\u00e9rentes traditions?<\/strong><\/p>\n<p>David Bontemps\u00a0: \u00ab\u00a0Absolument. Autant des compositions o\u00f9 je stylise des rythmes et des m\u00e9lodies de mon cr\u00fb qui font \u00e9cho \u00e0 ces traditions. De plus, dans la pi\u00e8ce de th\u00e9\u00e2tre de Faubert Bolivar sur laquelle est bas\u00e9 mon op\u00e9ra, il y a un chant traditionnel vaudou que j\u2019ai repris et stylis\u00e9 et trait\u00e9 \u00e0 ma mani\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_53374\" aria-describedby=\"caption-attachment-53374\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-53374 size-large\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2018\/04\/Suzanne-Taffot-Soprano-1-c-festival-dopera-de-quebec-681x1024.jpg\" alt=\"Suzanne Taffot, soprano. (Photo: courtoisie)\" width=\"640\" height=\"962\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2018\/04\/Suzanne-Taffot-Soprano-1-c-festival-dopera-de-quebec-681x1024.jpg 681w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2018\/04\/Suzanne-Taffot-Soprano-1-c-festival-dopera-de-quebec-200x300.jpg 200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2018\/04\/Suzanne-Taffot-Soprano-1-c-festival-dopera-de-quebec-768x1154.jpg 768w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2018\/04\/Suzanne-Taffot-Soprano-1-c-festival-dopera-de-quebec.jpg 1024w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-53374\" class=\"wp-caption-text\">Suzanne Taffot, soprano, fait partie de la distribution de La Flambeau. (Photo: courtoisie)<\/figcaption><\/figure>\n<p><strong>LVM\u00a0: Pourquoi le titre est-il \u00ab\u00a0la\u00a0\u00bb flambeau, et non \u00ab\u00a0le\u00a0\u00bb.<\/strong><\/p>\n<p><strong>David Bontemps\u00a0<\/strong>: \u00ab\u00a0L\u2019\u0153uvre de Faubert Bolivar est digressive \u00e0 plusieurs \u00e9gards. \u00c7a commence d\u00e8s le titre. De cette mani\u00e8re, il veut nous confronter \u00e0 nos id\u00e9es re\u00e7ues, \u00e0 ce qu\u2019on croit \u00eatre la norme, une norme qui nous emp\u00eache d\u2019\u00eatre ouvert \u00e0 ce que l\u2019autre transporte comme imaginaire, comme fa\u00e7on d\u2019\u00eatre. Pour r\u00e9pondre de mani\u00e8re plus pr\u00e9cise, la flambeau est une famille d\u2019esprits dans le vaudou ha\u00eftien, \u00e0 laquelle une des protagonistes de la pi\u00e8ce est fid\u00e8le. C\u2019est un univers secret, tout un imaginaire qui sert justement \u00e0 faire en sorte de nous questionner\u00a0: sommes-nous vraiment capables de mettre de c\u00f4t\u00e9 nos a priori pour comprendre l\u2019autre qui est en face de nous?\u00a0\u00bb<\/p>\n<p><strong>LVM\u00a0: De quoi parle le sc\u00e9nario?<\/strong><\/p>\n<p><strong>David Bontemps<\/strong>\u00a0: \u00ab\u00a0C\u2019est l\u2019histoire d\u2019un couple dysfonctionnel compos\u00e9 de monsieur, un intellectuel qui a de beaux principes et parle de la R\u00e9publique, et de madame, qui semble frapp\u00e9e de folie. Elle parle \u00e0 sa m\u00e8re et \u00e0 son oncle, tous deux d\u00e9funts. Le couple embauche une servante, m\u00e9nag\u00e8re issue de la classe ouvri\u00e8re, et monsieur, frapp\u00e9 par sa beaut\u00e9, tente de l\u2019attirer dans ses filets et va finir par la violer. Elle prend la fuite et plus tard, un parfait inconnu arrive dans le salon de monsieur et proc\u00e8de \u00e0 son jugement.\u00a0\u00bb<\/p>\n<p><em>[NDLR\u00a0: nous avons volontairement tronqu\u00e9 la fin de la r\u00e9ponse de David Bontemps afin de ne pas r\u00e9v\u00e9ler la fin de l\u2019histoire]<\/em><\/p>\n<p><strong>LVM\u00a0: Pouvez-vous nous en dire plus sur Faubert Bolivar?<\/strong><\/p>\n<p><strong>David Bontemps\u00a0:<\/strong> \u00ab\u00a0Nous nous sommes rencontr\u00e9s \u00e0 la Facult\u00e9 de droit, \u00e0 Port-au-Prince, et il enseigne maintenant la philosophie en Martinique. C\u2019est \u00e0 la faveur d\u2019un prix qu\u2019il a re\u00e7u pour sa pi\u00e8ce,<em> La Flambeau<\/em>, qu\u2019il m\u2019a envoy\u00e9 celle-ci, en 2014, et cela m\u2019a inspir\u00e9 \u00e0 \u00e9crire un op\u00e9ra. Comme Faubert Bolivar est \u00e9galement juriste, il y a beaucoup de r\u00e9f\u00e9rences \u00e0 la justice dans la pi\u00e8ce.\u00a0\u00bb<\/p>\n<p><strong>La Flambeau, op\u00e9ra de David Bontemps, adaptation d\u2019une pi\u00e8ce de Faubert Bolivar, avec Suzanne Taffot, soprano, Catherine Daniel, mezzo-soprano, Paul Williamson, t\u00e9nor, et Brandon Coleman, baryton-basse, dans une mise en sc\u00e8ne de Mariah Inger, sous la direction d\u2019Alain Trudel.<\/strong><\/p>\n<p><strong>Le 7 f\u00e9vrier 2023, 19h39, salle Pierre-Mercure.<\/strong> <a href=\"https:\/\/orchestre.ca\/la-flambeau-premiere-mondiale\/\" target=\"_blank\" rel=\"noopener\">D\u00c9TAILS<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><em>Inscrivez-vous \u00e0 notre infolettre! La musique classique et l&rsquo;op\u00e9ra en 5 minutes, chaque jour<\/em> \u00a0<span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/ludwig-van.us9.list-manage.com\/subscribe?u=4f785cb3f9058f2393ccad035&amp;id=b9b160c032\" target=\"_blank\" rel=\"noopener noreferrer\">ICI\u00a0<\/a><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du Mois de l\u2019histoire des Noirs, l\u2019Orchestre classique de Montr\u00e9al pr\u00e9sente cette semaine en premi\u00e8re mondiale l\u2019op\u00e9ra La Flambeau, de David Bontemps, sur un livret de Faubert Bolivar. Entretien avec le compositeur montr\u00e9alais d\u2019origine ha\u00eftienne, qui nous parle de sa cr\u00e9ation.<\/p>\n","protected":false},"author":51,"featured_media":75089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false},"categories":[42065,10956,10998],"tags":[42066,38749],"yst_prominent_words":[12034,24072,14707,9811,10167],"acf":[],"jetpack_featured_media_url":"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2023\/02\/David-Bontemps-cr-Kevin-Calixte.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bdYt-jwZ","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/75081"}],"collection":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/comments?post=75081"}],"version-history":[{"count":7,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/75081\/revisions"}],"predecessor-version":[{"id":75090,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/75081\/revisions\/75090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media\/75089"}],"wp:attachment":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media?parent=75081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/categories?post=75081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/tags?post=75081"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/yst_prominent_words?post=75081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}