{"id":65595,"date":"2021-01-13T14:43:08","date_gmt":"2021-01-13T19:43:08","guid":{"rendered":"https:\/\/www.ludwig-van.com\/montreal\/?p=65595"},"modified":"2021-01-13T14:43:08","modified_gmt":"2021-01-13T19:43:08","slug":"nouvelle-le-conseil-quebecois-de-la-musique-remettra-son-prix-hommage-a-kent-nagano-au-gala-des-prix-opus","status":"publish","type":"post","link":"https:\/\/www.ludwig-van.com\/montreal\/2021\/01\/13\/nouvelle-le-conseil-quebecois-de-la-musique-remettra-son-prix-hommage-a-kent-nagano-au-gala-des-prix-opus\/","title":{"rendered":"NOUVELLE | Le Conseil qu\u00e9b\u00e9cois de la musique remettra son prix hommage \u00e0 Kent Nagano au gala des prix Opus"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-63914\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/02\/Nagano-cover.jpg\" alt=\"\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/02\/Nagano-cover.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/02\/Nagano-cover-300x157.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/02\/Nagano-cover-1024x536.jpg 1024w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/02\/Nagano-cover-768x402.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Le <strong>Conseil qu\u00e9b\u00e9cois de la musique<\/strong> a annonc\u00e9 que le prochain prix hommage, qui vise \u00e0 reconna\u00eetre la contribution exceptionnelle d&rsquo;un individu \u00e0 la vie musicale qu\u00e9b\u00e9coise, sera remis \u00e0 <strong>Kent Nagano<\/strong> \u00e0 l&rsquo;occasion de son prochain gala, qui aura lieu le 7 f\u00e9vrier \u00e0 16 h.<\/p>\n<p>Par les ann\u00e9es pass\u00e9es, le prix hommage du CQM a \u00e9t\u00e9 remis \u00e0 Lorraine Vaillancourt, Johanne Goyette et Jacqueline Desmarais, entre autres. Il s&rsquo;agit toujours d&rsquo;un moment fort du gala alors que ces personnes qui ont consacr\u00e9 pendant des ann\u00e9es, parfois toute leur vie, le plus clair de leur temps et de leur \u00e9nergie au service de la musique. Au sujet de la contribution de Kent Nagano, le communiqu\u00e9 de presse du Conseil qu\u00e9b\u00e9cois de la musique dit ceci:<\/p>\n<p>\u00ab\u00a0<em>Au cours des seize ann\u00e9es consacr\u00e9es \u00e0 la direction musicale et artistique de l&rsquo;Orchestre symphonique de Montr\u00e9al, Kent Nagano a su rehausser et maintenir le niveau d&rsquo;excellence de cette institution centrale \u00e0 la vie artistique qu\u00e9b\u00e9coise. En plus des nombreux enregistrements et des tourn\u00e9es qui ont valu \u00e0 l&rsquo;orchestre une r\u00e9putation internationale, maestro Nagano a eu \u00e0 cour son enracinement dans le tissu social. Entre autres, les concerts ext\u00e9rieurs gratuits et les visites aux communaut\u00e9s autochtones et inuites du Nord qu\u00e9b\u00e9cois et canadien t\u00e9moignent d&rsquo;un d\u00e9sir de cr\u00e9er des liens avec la population. \u00a0Par ailleurs, en plus de permettre aux m\u00e9lomanes d&rsquo;ici et d&rsquo;ailleurs de d\u00e9couvrir le travail d&rsquo;interpr\u00e8tes, de compositeurs et d&rsquo;artistes qu\u00e9b\u00e9cois, Kent Nagano a \u00e9galement propos\u00e9 des spectacles mettant en valeur des embl\u00e8mes de la culture populaire tels que le Canadien de Montr\u00e9al. Nous lui devons en outre la Vir\u00e9e classique et une panoplie d&rsquo;\u00e9v\u00e9nements atypiques qui ont permis d&rsquo;initier un vaste public \u00e0 la musique symphonique. Cela, sans n\u00e9gliger la rel\u00e8ve qu&rsquo;il a soutenue \u00e0 diverses reprises, notamment par ses implications aupr\u00e8s des grandes \u00e9coles de musique montr\u00e9alaise. Pour toujours, son nom sera associ\u00e9 \u00e0 celui de la Maison symphonique, un r\u00eave qu&rsquo;il a concr\u00e9tis\u00e9 en 2011 et qui positionne Montr\u00e9al parmi les grandes sc\u00e8nes musicales du monde.\u00a0\u00bb<\/em><\/p>\n<p>Il va sans dire que Kent Nagano m\u00e9rite amplement cette reconnaissance, au terme de ces 16 ans comme directeur musical et artistique de l&rsquo;OSM. Notre seul regret est de ne pas avoir eu la chance de lui dire un v\u00e9ritable au revoir, puisque ses derniers concerts ont \u00e9t\u00e9 annul\u00e9s en raison de la pand\u00e9mie. Esp\u00e9rons que ce n&rsquo;est que partie remise.<\/p>\n<h2>Prestations virtuelles<\/h2>\n<p>Le gala des prix Opus aura lieu le 7 f\u00e9vrier de fa\u00e7on virtuelle et sera diffus\u00e9 en direct par <a href=\"https:\/\/www.facebook.com\/LaFabriqueculturelle.tv\" target=\"_blank\" rel=\"noopener noreferrer\">La Fabrique culturelle.<\/a> Des prestations musicales seront offertes par la soprano Karina Gauvin, la contralto Marie-Nicole Lemieux, le pianiste Olivier Godin, le trio jazz Emie R Roussel Trio et le groupe de musique traditionnelle qu\u00e9b\u00e9coise Le Vent du Nord.<\/p>\n<p>L&rsquo;\u00e9v\u00e9nement sera anim\u00e9 par Marc Hervieux, chanteur et animateur d&rsquo;ICI Musique, alors que Catherine Perrin conduira des entrevues avec des invit\u00e9s-surprises. Il va sans dire que nous serons au rendez-vous. Vous pourrez lire un compte-rendu le jour m\u00eame sur Ludwig van Montr\u00e9al.<\/p>\n<p><a href=\"https:\/\/www.ludwig-van.com\/montreal\/2020\/11\/25\/nouvelle-decouvrez-finalistes-prochains-prix-opus\/\" target=\"_blank\" rel=\"noopener noreferrer\">POUR CONNA\u00ceTRE LES FINALISTES AUX PRIX OPUS.<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>LIRE AUSSI:<\/h2>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"VTE74p9U0X\"><p><a href=\"https:\/\/www.ludwig-van.com\/montreal\/2020\/11\/25\/nouvelle-decouvrez-finalistes-prochains-prix-opus\/\">NOUVELLE | D\u00e9couvrez qui sont tous les finalistes des prochains Prix Opus!<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0NOUVELLE | D\u00e9couvrez qui sont tous les finalistes des prochains Prix Opus!\u00a0\u00bb &#8212; Ludwig Van Montreal\" src=\"https:\/\/www.ludwig-van.com\/montreal\/2020\/11\/25\/nouvelle-decouvrez-finalistes-prochains-prix-opus\/embed\/#?secret=VTE74p9U0X\" data-secret=\"VTE74p9U0X\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil qu\u00e9b\u00e9cois de la musique a annonc\u00e9 que le prochain prix hommage, qui vise \u00e0 reconna\u00eetre la contribution exceptionnelle d&rsquo;un individu \u00e0 la vie musicale qu\u00e9b\u00e9coise, sera remis \u00e0 Kent Nagano \u00e0 l&rsquo;occasion de son prochain gala, qui aura lieu le 7 f\u00e9vrier \u00e0 16 h.<\/p>\n","protected":false},"author":51,"featured_media":63914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false},"categories":[41122,10956,10992],"tags":[27997,1858,4485,15875],"yst_prominent_words":[17174,9840,15878,13015,17805,10441,10436,41144,41145,7694,9811,10440,9857,18297,10975,12519,15874,16676,9839,9882],"acf":[],"jetpack_featured_media_url":"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/02\/Nagano-cover.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bdYt-h3Z","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/65595"}],"collection":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/comments?post=65595"}],"version-history":[{"count":2,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/65595\/revisions"}],"predecessor-version":[{"id":65597,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/65595\/revisions\/65597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media\/63914"}],"wp:attachment":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media?parent=65595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/categories?post=65595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/tags?post=65595"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/yst_prominent_words?post=65595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}