{"id":65376,"date":"2020-11-12T13:01:45","date_gmt":"2020-11-12T18:01:45","guid":{"rendered":"https:\/\/www.ludwig-van.com\/montreal\/?p=65376"},"modified":"2020-11-12T13:01:45","modified_gmt":"2020-11-12T18:01:45","slug":"nouvelle-losm-lance-projet-enfants-autistes-michel-phaneuf","status":"publish","type":"post","link":"https:\/\/www.ludwig-van.com\/montreal\/2020\/11\/12\/nouvelle-losm-lance-projet-enfants-autistes-michel-phaneuf\/","title":{"rendered":"NOUVELLE  | L&rsquo;OSM lance un projet pour les enfants autistes avec Michel Phaneuf"},"content":{"rendered":"<figure id=\"attachment_65378\" aria-describedby=\"caption-attachment-65378\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-65378 size-full\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/11\/osmose-Michel-Phaneuf.jpg\" alt=\"\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/11\/osmose-Michel-Phaneuf.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/11\/osmose-Michel-Phaneuf-300x157.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/11\/osmose-Michel-Phaneuf-1024x536.jpg 1024w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/11\/osmose-Michel-Phaneuf-768x402.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-65378\" class=\"wp-caption-text\">\u00c0 gauche: Michel Phaneuf. \u00c0 droite: une jeune \u00e9l\u00e8ve participante au programme OSMose. (Photos: courtoisie de l&rsquo;OSM)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>L&rsquo;Orchestre symphonique de Montr\u00e9al<\/strong> s&rsquo;associe au sommelier, auteur et philanthrope <strong>Michel <\/strong>Phaneuf pour lancer le projet OSMose, qui sera d\u00e9di\u00e9 aux enfants pr\u00e9sentant un trouble du spectre de l\u2019autisme (TSA). Cette initiative est financ\u00e9e par Michel Phaneuf, gr\u00e2ce \u00e0 un don de ce dernier de 100 000 $ r\u00e9partis sur trois ans.<\/p>\n<p>Le programme a commenc\u00e9 discr\u00e8tement \u00e0 l\u2019automne 2019 \u00e0 l\u2019\u00e9cole Saint-Etienne du Centre de services scolaires de Montr\u00e9al, aupr\u00e8s de trois classes d\u2019\u00e9l\u00e8ves TSA ainsi que d\u2019une classe r\u00e9guli\u00e8re. Depuis d\u00e9cembre 2019, les enfants ont re\u00e7u, en plus de leur s\u00e9ance de musicoth\u00e9rapie hebdomadaire avec Nathalie Leroux, la visite de musiciens de l\u2019OSM et de son chef assistant, Thomas Le Duc-Moreau.<\/p>\n<p>L&rsquo;id\u00e9e, c&rsquo;est de permettre \u00e0 ces enfants dont les besoins particuliers ne permettent pas n\u00e9cessairement de profiter des activit\u00e9s du volet jeunesse de l&rsquo;OSM, d&rsquo;avoir quand m\u00eame acc\u00e8s \u00e0 l&rsquo;exp\u00e9rience du concert. C&rsquo;est pourquoi une gamme de ressources p\u00e9dagogiques sp\u00e9cialis\u00e9es seront d\u00e9velopp\u00e9es pour eux durant l\u2019hiver et le printemps 2021, permettant ainsi de concr\u00e9tiser les apprentissages du projet avec des outils \u00e9ducatifs cibl\u00e9s pour les publics \u00e0 besoins particuliers.<\/p>\n<p>Il est \u00e9videmment pr\u00e9vu que les participants du programme OSMose se rendent \u00e9ventuellement \u00e0 la Maison symphonique o\u00f9, accompagn\u00e9s par les musiciens de l\u2019Orchestre, ils se familiariseront avec les lieux. Toute au long de l&rsquo;ann\u00e9e 2021, il seront \u00e9galement invit\u00e9s \u00e0 participer \u00e0 la cr\u00e9ation d\u2019une \u0153uvre collaborative, anim\u00e9e par leur professeur.<\/p>\n<p>L\u2019aboutissement du projet se fera lors d\u2019un grand concert adapt\u00e9, alors que tous les \u00e9l\u00e8ves de l\u2019\u00e9cole Saint-Etienne seront invit\u00e9s \u00e0 la Maison symphonique, et dont les d\u00e9tails seront d\u00e9voil\u00e9s plus tard.<\/p>\n<p>En 2016, Michel Phaneuf s&rsquo;engageait s\u00e9rieusement dans la philanthropie en vendant sa cave \u00e0 vins personnelle pour cr\u00e9er un fonds de recherche sur la maladie de Parkinson, dont il est lui-m\u00eame atteint et qui lui a fait perdre une partie de son odorat, l&#8217;emp\u00eachant ainsi d&rsquo;appr\u00e9cier le vin autant qu&rsquo;avant. \u00c0 l&rsquo;\u00e9poque, j&rsquo;avais eu l&rsquo;occasion de le rencontrer \u00e0 son domicile, alors qu&rsquo;il \u00e9tait nomm\u00e9 <a href=\"https:\/\/plus.lapresse.ca\/screens\/6245d1d4-a174-4be3-ab89-5793f86bd790__7C___0.html\" target=\"_blank\" rel=\"noopener noreferrer\">Personnalit\u00e9 de la semaine dans La Presse<\/a>. Il m&rsquo;avait alors parl\u00e9 de son histoire et fait part de son int\u00e9r\u00eat pour la philanthropie. Il confiait alors:<\/p>\n<p>\u00ab On arrive \u00e0 un \u00e2ge, dans la vie, o\u00f9 l\u2019on r\u00e9alise que donner, c\u2019est tr\u00e8s bon pour soi. On ne se sent pas d\u00e9pouill\u00e9 de l\u2019argent qu\u2019on donne, au contraire, \u00e7a nous fait du bien. J\u2019aimerais tant que plus de gens le r\u00e9alisent. \u00c0 travers la philanthropie, on se sent utile, on sait qu\u2019on rend service, qu\u2019on a une raison d\u2019\u00eatre. \u00bb<\/p>\n<p>Ce sont maintenant les enfants qui pourront b\u00e9n\u00e9ficier de sa g\u00e9n\u00e9rosit\u00e9 \u00e0 travers ce nouveau projet avec l&rsquo;OSM.<\/p>\n<p>Au sujet de ce projet particulier, il d\u00e9clare:<\/p>\n<p>\u00ab J\u2019ai toujours consid\u00e9r\u00e9 deux choses essentielles \u00e0 l\u2019existence: la sant\u00e9 et la beaut\u00e9. Dans mon cas, la premi\u00e8re fut mon moteur, ma force; la seconde mon carburant, mon inspiration. Or, il est aussi d\u00e9montr\u00e9 que la beaut\u00e9 peut venir en aide \u00e0 la sant\u00e9. En misant sur les vertus th\u00e9rapeutiques de la musique pour stimuler et inspirer des enfants touch\u00e9s par un trouble du spectre de l\u2019autisme, le projet OSMose est porteur de grands espoirs. \u00bb<\/p>\n<p>&nbsp;<\/p>\n<h2>LIRE AUSSI:<\/h2>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"BIM7eIiv0i\"><p><a href=\"https:\/\/www.ludwig-van.com\/montreal\/2020\/10\/28\/nouvelle-losm-annonce-six-nouveaux-concerts-en-webdiffusion-dont-un-concert-dhalloween-gratuit\/\">NOUVELLE | L&rsquo;OSM annonce six nouveaux concerts en webdiffusion, dont un concert d&rsquo;Halloween gratuit<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0NOUVELLE | L&rsquo;OSM annonce six nouveaux concerts en webdiffusion, dont un concert d&rsquo;Halloween gratuit\u00a0\u00bb &#8212; Ludwig Van Montreal\" src=\"https:\/\/www.ludwig-van.com\/montreal\/2020\/10\/28\/nouvelle-losm-annonce-six-nouveaux-concerts-en-webdiffusion-dont-un-concert-dhalloween-gratuit\/embed\/#?secret=BIM7eIiv0i\" data-secret=\"BIM7eIiv0i\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Orchestre symphonique de Montr\u00e9al s&rsquo;associe au sommelier, auteur et philanthrope Michel Phaneuf pour lancer le projet OSMose, qui sera d\u00e9di\u00e9 aux enfants pr\u00e9sentant un trouble du spectre de l\u2019autisme (TSA). Cette initiative est financ\u00e9e par Michel Phaneuf, gr\u00e2ce \u00e0 un don de ce dernier de 100 000 $ r\u00e9partis sur trois ans.<\/p>\n","protected":false},"author":51,"featured_media":65378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false},"categories":[37357,10956,10992],"tags":[40839,40838,2542,40837],"yst_prominent_words":[40827,9842,11255,40830,10443,9869,11462,40823,40832,40824,40825,8313,40831,11543,40836,11240,40835,9839,40834,40833],"acf":[],"jetpack_featured_media_url":"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/11\/osmose-Michel-Phaneuf.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bdYt-h0s","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/65376"}],"collection":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/comments?post=65376"}],"version-history":[{"count":2,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/65376\/revisions"}],"predecessor-version":[{"id":65380,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/65376\/revisions\/65380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media\/65378"}],"wp:attachment":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media?parent=65376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/categories?post=65376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/tags?post=65376"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/yst_prominent_words?post=65376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}