{"id":64907,"date":"2020-08-16T14:31:45","date_gmt":"2020-08-16T18:31:45","guid":{"rendered":"https:\/\/www.ludwig-van.com\/montreal\/?p=64907"},"modified":"2020-08-16T14:31:45","modified_gmt":"2020-08-16T18:31:45","slug":"nouvelle-laureats-prix-orford-musique-devoiles","status":"publish","type":"post","link":"https:\/\/www.ludwig-van.com\/montreal\/2020\/08\/16\/nouvelle-laureats-prix-orford-musique-devoiles\/","title":{"rendered":"NOUVELLE | Les laur\u00e9ats des Prix Orford Musique d\u00e9voil\u00e9s"},"content":{"rendered":"<figure id=\"attachment_64908\" aria-describedby=\"caption-attachment-64908\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-64908\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/08\/Prix-Orford-cover.jpg\" alt=\"\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/08\/Prix-Orford-cover.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/08\/Prix-Orford-cover-300x157.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/08\/Prix-Orford-cover-1024x536.jpg 1024w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/08\/Prix-Orford-cover-768x402.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-64908\" class=\"wp-caption-text\">Poom Prommachart, Matt Dupont, Abby Walsh. (Photos: pages Facebook des artistes)<\/figcaption><\/figure>\n<p>La grande finale des Prix Orford Musique avait lieu hier soir. Les laur\u00e9ats ont \u00e9t\u00e9 d\u00e9voil\u00e9s aujourd&rsquo;hui.<\/p>\n<p>C&rsquo;est <strong>Poom Prommachart<\/strong>, pianiste et \u00e9tudiant \u00e0 l&rsquo;Universit\u00e9 de Montr\u00e9al, qui a remport\u00e9 le premier prix. Il recevra donc recevra une bourse compl\u00e8te pour un s\u00e9jour de deux semaines \u00e0 l\u2019Acad\u00e9mie Orford Musique 2020, une invitation \u00e0 participer au Festival Orford Musique 2021, une s\u00e9ance d\u2019enregistrement audio-vid\u00e9o professionnelle, des s\u00e9ances de coaching sur mesure, des occasions de concerts ainsi qu\u2019un prix en argent, remis par la Municipalit\u00e9 du Canton d\u2019Orford, partenaire officiel du Prix Orford Musique 2020.<\/p>\n<p>Le deuxi\u00e8me prix est all\u00e9 \u00e0 <strong>Matt Dupont<\/strong>, harpiste, \u00e9galement \u00e9tudiant \u00e0 l&rsquo;Universit\u00e9 de Montr\u00e9al. Il se m\u00e9rite ainsi une bourse compl\u00e8te pour un s\u00e9jour de deux semaines \u00e0 l\u2019Acad\u00e9mie Orford Musique 2020, une s\u00e9ance photo professionnelle ainsi qu\u2019un prix en argent, remis par M. Serge Martin.<\/p>\n<p>Le troisi\u00e8me prix ainsi que le prix Coup de c\u0153ur du public vont \u00e0 la violoniste <strong>Abby Walsh<\/strong>, \u00e9tudiante au Conservatoire de musique de Montr\u00e9al. Comme gagnante du troisi\u00e8me prix, elle recevra une bourse compl\u00e8te pour un s\u00e9jour d&rsquo;une semaine \u00e0 l&rsquo;Acad\u00e9mie Orford Musique 2021 ainsi qu&rsquo;un prix en argent offert par M. Deslauriers. Comme gagnante du Coup de coeur, elle recevra \u00e9galement une invitation et un s\u00e9jour \u00e0 Orford Musique, ainsi qu\u2019un prix en argent, offert par la Municipalit\u00e9 du Canton d\u2019Orford.<\/p>\n<p>Au total, huit musiciens r\u00e9sidant au Qu\u00e9bec qui avaient \u00e9t\u00e9 s\u00e9lectionn\u00e9s pour participer \u00e0 cette \u00e9dition sp\u00e9ciale du Prix Orford Musique.<\/p>\n<p>Toutes nos f\u00e9licitations aux laur\u00e9ats.<\/p>\n<p>&nbsp;<\/p>\n<h2>LIRE AUSSI:<\/h2>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"Ic7S2oaYoO\"><p><a href=\"https:\/\/www.ludwig-van.com\/montreal\/2020\/08\/10\/nouvelle-quatre-premieres-mondiales-aux-prix-azrieli-de-musique\/\">NOUVELLE | Quatre premi\u00e8res mondiales aux Prix Azrieli de musique en octobre sur medici.tv<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0NOUVELLE | Quatre premi\u00e8res mondiales aux Prix Azrieli de musique en octobre sur medici.tv\u00a0\u00bb &#8212; Ludwig Van Montreal\" src=\"https:\/\/www.ludwig-van.com\/montreal\/2020\/08\/10\/nouvelle-quatre-premieres-mondiales-aux-prix-azrieli-de-musique\/embed\/#?secret=Ic7S2oaYoO\" data-secret=\"Ic7S2oaYoO\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La grande finale des Prix Orford Musique avait lieu hier soir. Les laur\u00e9ats ont \u00e9t\u00e9 d\u00e9voil\u00e9s aujourd&rsquo;hui.\u00a0Poom Prommachart remporte le premier prix.<\/p>\n","protected":false},"author":51,"featured_media":64908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false},"categories":[37357,10956,10992],"tags":[4135,40020,40022,40021,40019],"yst_prominent_words":[24327,25347,40013,21691,21690,40006,40018,40005,40004,39865,24160,40017,40012,22105,21719,40007,24326,40016,40011,40015],"acf":[],"jetpack_featured_media_url":"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/08\/Prix-Orford-cover.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bdYt-gST","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/64907"}],"collection":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/comments?post=64907"}],"version-history":[{"count":1,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/64907\/revisions"}],"predecessor-version":[{"id":64909,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/64907\/revisions\/64909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media\/64908"}],"wp:attachment":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media?parent=64907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/categories?post=64907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/tags?post=64907"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/yst_prominent_words?post=64907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}