{"id":64298,"date":"2020-03-18T18:06:10","date_gmt":"2020-03-18T22:06:10","guid":{"rendered":"https:\/\/www.ludwig-van.com\/montreal\/?p=64298"},"modified":"2021-03-07T11:26:50","modified_gmt":"2021-03-07T16:26:50","slug":"nouvelle-losm-diffusera-trois-concerts-virtuels-semaine-a-compter-18-mars","status":"publish","type":"post","link":"https:\/\/www.ludwig-van.com\/montreal\/2020\/03\/18\/nouvelle-losm-diffusera-trois-concerts-virtuels-semaine-a-compter-18-mars\/","title":{"rendered":"NOUVELLE | L&rsquo;OSM diffusera trois concerts virtuels par semaine \u00e0 compter du 18 mars"},"content":{"rendered":"<figure id=\"attachment_63739\" aria-describedby=\"caption-attachment-63739\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-63739\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/01\/Nagano-cover.jpg\" alt=\"\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/01\/Nagano-cover.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/01\/Nagano-cover-300x157.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/01\/Nagano-cover-1024x536.jpg 1024w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/01\/Nagano-cover-768x402.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-63739\" class=\"wp-caption-text\">Kent Nagano dirige l&rsquo;OSM pour sa derni\u00e8re saison cette ann\u00e9e. (Photo: courtoisie de l&rsquo;OSM)<\/figcaption><\/figure>\n<p><strong>L&rsquo;Orchestre symphonique de Montr\u00e9al<\/strong> a annonc\u00e9 aujourd&rsquo;hui la diffusion de concerts les lundis, mercredis et vendredis pendant la p\u00e9riode d\u2019annulation des concerts en raison du COVID-19, et ce, \u00e0 compter de ce soir, 18 mars, 20 h, <a href=\"https:\/\/www.osm.ca\/fr\/ecouter-et-visionner\/\" target=\"_blank\" rel=\"noopener noreferrer\">sur son site web.\u00a0<\/a><\/p>\n<p>Le premier concert vid\u00e9o sera une rediffusion du concert enregistr\u00e9 le lundi 17 mars 2014 au Konzerthaus de Vienne, en Autriche, une coproduction OSM \/ Medici.tv. Au programme: la Symphonie no 7 en si mineur, \u00ab Chant de la nuit \u00bb, de Gustav Mahler.<\/p>\n<p>Le vendredi 20 mars \u00e0 12h00 (diffusion jusqu\u2019au 23 mars 20h00) on pourra voir et entendre l&rsquo;OSM sous la direction de Kent Nagano dans la\u00a0 Symphonie no 9 en mi mineur, B. 178, \u00ab Du Nouveau Monde \u00bb, de Dvo\u0159\u00e1k. Ce concert a \u00e9t\u00e9 enregistr\u00e9 le mercredi 31 mai 2017 \u00e0 la Maison symphonique de Montr\u00e9al, une coproduction OSM \/ Prodcan pour Medici.tv.<\/p>\n<p>Les concerts des semaines suivantes, s&rsquo;il y a lieu, seront annonc\u00e9s au fur et \u00e0 mesure. C&rsquo;est une excellent nouvelle pour les m\u00e9lomanes priv\u00e9s de concerts en cette p\u00e9riode de confinement. Bravo \u00e0 l&rsquo;OSM pour cette initiative!<\/p>\n<p><a href=\"https:\/\/www.osm.ca\/fr\/ecouter-et-visionner\/\" target=\"_blank\" rel=\"noopener noreferrer\">POUR ACC\u00c9DER AUX CONCERTS EN LIGNE<\/a><\/p>\n<h2><em>Inscrivez-vous \u00e0 notre infolettre! La musique classique et l&rsquo;op\u00e9ra en 5 minutes, chaque jour<\/em> \u00a0<span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/ludwig-van.us9.list-manage.com\/subscribe?u=4f785cb3f9058f2393ccad035&amp;id=b9b160c032\" target=\"_blank\" rel=\"noopener noreferrer\">ICI\u00a0<\/a><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Orchestre symphonique de Montr\u00e9al a annonc\u00e9 aujourd&rsquo;hui la diffusion de concerts les lundis, mercredis et vendredis pendant la p\u00e9riode d\u2019annulation des concerts en raison du COVID-19, et ce, \u00e0 compter de ce soir, 18 mars, 20 h, sur son site web. <\/p>\n","protected":false},"author":51,"featured_media":63739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false},"categories":[37357,10956,10992],"tags":[4135,4485,2542],"yst_prominent_words":[10190,7202,8858,29984,38608,25417,15957,10441,10436,10443,16404,38609,7694,10440,13255,38610,10109,11819,9839,9870],"acf":[],"jetpack_featured_media_url":"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2020\/01\/Nagano-cover.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bdYt-gJ4","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/64298"}],"collection":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/comments?post=64298"}],"version-history":[{"count":3,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/64298\/revisions"}],"predecessor-version":[{"id":66121,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/64298\/revisions\/66121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media\/63739"}],"wp:attachment":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media?parent=64298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/categories?post=64298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/tags?post=64298"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/yst_prominent_words?post=64298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}