{"id":62261,"date":"2019-10-17T13:47:33","date_gmt":"2019-10-17T17:47:33","guid":{"rendered":"https:\/\/www.ludwig-van.com\/montreal\/?p=62261"},"modified":"2019-10-19T12:04:26","modified_gmt":"2019-10-19T16:04:26","slug":"nouvelle-jean-francois-lapointe-nomme-directeur-artistique-de-lopera-de-quebec","status":"publish","type":"post","link":"https:\/\/www.ludwig-van.com\/montreal\/2019\/10\/17\/nouvelle-jean-francois-lapointe-nomme-directeur-artistique-de-lopera-de-quebec\/","title":{"rendered":"NOUVELLE | Jean-Fran\u00e7ois Lapointe nomm\u00e9 directeur artistique de l&rsquo;Op\u00e9ra de Qu\u00e9bec"},"content":{"rendered":"<figure id=\"attachment_62262\" aria-describedby=\"caption-attachment-62262\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-62262\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/redim_JF-Lapointe.jpg\" alt=\"\" width=\"1200\" height=\"857\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/redim_JF-Lapointe.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/redim_JF-Lapointe-300x214.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/redim_JF-Lapointe-768x548.jpg 768w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/redim_JF-Lapointe-1024x731.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-62262\" class=\"wp-caption-text\">Le baryton Jean-Fran\u00e7ois Lapointe prendra la rel\u00e8ve de Gr\u00e9goire Legendre en tant que directeur artistique de l&rsquo;Op\u00e9ra de Qu\u00e9bec.<\/figcaption><\/figure>\n<p>Grand changement en vue \u00e0 l&rsquo;<strong>Op\u00e9ra de Qu\u00e9bec<\/strong> : <strong>Gr\u00e9goire Legendre<\/strong> quitte la direction artistique de l&rsquo;organisme, qu&rsquo;il pilotait depuis 25 ans. Le pr\u00e9sident du conseil d\u2019administration, M. Pierre A. Goulet, annon\u00e7ait ce matin par voie de communiqu\u00e9 que c&rsquo;est le baryton de renomm\u00e9e internationale <strong>Jean-Fran\u00e7ois Lapointe<\/strong> qui lui succ\u00e9dera \u00e0 partir de septembre 2020.<\/p>\n<p style=\"font-weight: 400;\"><strong>Gr\u00e9goire Legendre<\/strong> a men\u00e9 \u00e0 bien de nombreuses r\u00e9alisations d&rsquo;envergure \u00e0 l&rsquo;Op\u00e9ra de Qu\u00e9bec, une des plus remarquables \u00e9tant sans doute le succ\u00e8s du Festival d&rsquo;op\u00e9ra de Qu\u00e9bec. Depuis sa mise sur pied en 2011, le Festival a pr\u00e9sent\u00e9 de nombreuses productions audacieuses, souvent dans des mises en sc\u00e8ne de Robert Lepage, et inaugur\u00e9 des partenariats avec des compagnies d&rsquo;op\u00e9ra prestigieuses telles le <em>Metropolitan Opera<\/em> de New York.<\/p>\n<p style=\"font-weight: 400;\">L&rsquo;engagement passionn\u00e9 de Gr\u00e9goire Legendre lui a valu plusieurs r\u00e9compenses : un <em>Ruby Award<\/em> du magazine\u00a0<em>Opera Canada\u00a0<\/em>(2016), l\u2019Ordre du Canada (2015) pour sa contribution \u00e0 l\u2019essor de l\u2019art lyrique au pays, ainsi qu\u2019un prix Opus du Conseil qu\u00e9b\u00e9cois de la musique comme directeur artistique de l\u2019ann\u00e9e en 2012.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"font-weight: 400;\">\u00ab\u00a0Tout au long de ces 25 ann\u00e9es, l\u2019Op\u00e9ra de Qu\u00e9bec m\u2019a apport\u00e9 une multitude de moments inoubliables. J\u2019esp\u00e8re qu\u2019il en a \u00e9t\u00e9 de m\u00eame pour le public. Il sera bient\u00f4t temps de passer le flambeau, et je reconnais en Jean-Fran\u00e7ois Lapointe la personne qui le portera avec fiert\u00e9, comp\u00e9tence et une grande exp\u00e9rience. En d\u00e9cembre 2020, je prendrai donc une retraite bien m\u00e9rit\u00e9e, apr\u00e8s une p\u00e9riode de transition de quatre mois \u00e0 la direction g\u00e9n\u00e9rale.\u00a0\u00bb &#8211; Gr\u00e9goire Legendre<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h2>Jean-Fran\u00e7ois Lapointe<\/h2>\n<p style=\"font-weight: 400;\">Son successeur am\u00e8ne une r\u00e9putation et une exp\u00e9rience \u00e0 la hauteur de la t\u00e2che : <strong>Jean-Fran\u00e7ois Lapointe<\/strong> m\u00e8ne depuis plusieurs ann\u00e9es une carri\u00e8re enviable sur les plus grandes sc\u00e8nes d&rsquo;op\u00e9ra. Il est reconnu comme un des meilleurs interpr\u00e8tes de Pell\u00e9as dans le <em>Pell\u00e9as et M\u00e9lisande<\/em> de Debussy, mais son profil Wikipedia chiffre le nombre de r\u00f4les qu&rsquo;il aurait jou\u00e9s aux alentours de soixante.<\/p>\n<p>Originaire du Saguenay-Lac-Saint-Jean, Lapointe a \u00e9t\u00e9 form\u00e9 d&rsquo;abord \u00e0 l&rsquo;Universit\u00e9 Laval aupr\u00e8s de Louise Andr\u00e9, avant de poursuivre sa formation aux \u00c9tats-Unis aupr\u00e8s de Martial Singher. Il a toujours maintenu un lien tr\u00e8s fort avec le Qu\u00e9bec, m\u00eame \u00e0 travers ses nombreux engagements europ\u00e9ens, et se trouve \u00e0 \u00eatre de nouveau rattach\u00e9 \u00e0 son <em>alma mater<\/em> puisqu&rsquo;il enseigne depuis quelques ann\u00e9es \u00e0 l\u2019Universit\u00e9 Laval. Le public de Qu\u00e9bec avait d\u2019ailleurs pu l\u2019entendre dans le r\u00f4le-titre d\u2019<em>Eug\u00e8ne On\u00e9guine<\/em>, en 2011.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00ab\u00a0Il ne fait nul doute que la connaissance profonde de Jean-Fran\u00e7ois Lapointe du milieu op\u00e9ratique, son vaste r\u00e9seau de contacts ainsi que son exp\u00e9rience en tant que gestionnaire seront des atouts pr\u00e9cieux pour le futur de notre organisation.\u00a0\u00bb &#8211; Pierre A. Goulet<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">Il s&rsquo;est aussi forg\u00e9 la main \u00e0 la direction g\u00e9n\u00e9rale et artistique d&rsquo;une maison d&rsquo;op\u00e9ra en assumant ces r\u00f4les aupr\u00e8s de\u00a0la <strong>Soci\u00e9t\u00e9 d\u2019art lyrique du Royaume<\/strong> pendant plusieurs ann\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"font-weight: 400;\">\u00ab\u00a0C\u2019est avec enthousiasme que je me joins \u00e0 l\u2019\u00e9quipe de l\u2019Op\u00e9ra de Qu\u00e9bec. Pour moi, cette nomination constitue une suite logique dans l\u2019\u00e9volution de mon parcours professionnel.\u00a0J\u2019ai toujours \u00e9t\u00e9 impliqu\u00e9 au niveau de la production d\u2019op\u00e9ras, et je me suis toujours int\u00e9ress\u00e9 \u00e0 l\u2019administration des arts. Mon mandat s\u2019inscrit ainsi dans un d\u00e9sir de continuit\u00e9, et je suis honor\u00e9 d\u2019avoir l\u2019occasion de poursuivre le travail remarquable effectu\u00e9 au fil des ans par Gr\u00e9goire Legendre.\u00a0\u00bb &#8211; Jean-Fran\u00e7ois Lapointe<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>Notre premi\u00e8re impression est que l&rsquo;<strong>Op\u00e9ra de Qu\u00e9bec<\/strong> a trouv\u00e9 un excellent successeur \u00e0<strong> Gr\u00e9goire Legendre<\/strong> et nous sommes curieux de conna\u00eetre les premiers projets du nouveau directeur artistique.<\/p>\n<p>&nbsp;<\/p>\n<h2>LIRE AUSSI :<\/h2>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"5z9WHC7cxn\"><p><a href=\"https:\/\/www.ludwig-van.com\/montreal\/2019\/10\/03\/rencontre-mado-lamotte-pourquoi-jaime-lopera\/\">RENCONTRE | Mado Lamotte : \u00ab\u00a0Pourquoi j&rsquo;aime l&rsquo;op\u00e9ra\u00a0\u00bb<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.ludwig-van.com\/montreal\/2019\/10\/03\/rencontre-mado-lamotte-pourquoi-jaime-lopera\/embed\/#?secret=5z9WHC7cxn\" data-secret=\"5z9WHC7cxn\" width=\"600\" height=\"338\" title=\"\u00ab\u00a0RENCONTRE | Mado Lamotte : \u00ab\u00a0Pourquoi j&rsquo;aime l&rsquo;op\u00e9ra\u00a0\u00bb\u00a0\u00bb &#8212; Ludwig Van Montreal\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grand changement en vue \u00e0 l&rsquo;Op\u00e9ra de Qu\u00e9bec : Gr\u00e9goire Legendre quitte la direction artistique de l&rsquo;organisme, qu&rsquo;il pilotait depuis 25 ans. Le pr\u00e9sident du conseil d\u2019administration, M. Pierre A. Goulet, annon\u00e7ait ce matin par voie de communiqu\u00e9 que c&rsquo;est le baryton de renomm\u00e9e internationale Jean-Fran\u00e7ois Lapointe qui lui succ\u00e9dera \u00e0 partir de septembre 2020.<\/p>\n","protected":false},"author":55,"featured_media":62329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false},"categories":[28802,10956,39],"tags":[28789,32191,27011],"yst_prominent_words":[9840,10654,11552,9856,9851,11678,35632,20891,35633,35630,11236,20330,10538,16489,17152,22116,35634,8139,9841,9838],"acf":[],"jetpack_featured_media_url":"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/JFLapointe_OdeQC.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bdYt-gcd","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/62261"}],"collection":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/comments?post=62261"}],"version-history":[{"count":6,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/62261\/revisions"}],"predecessor-version":[{"id":62273,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/62261\/revisions\/62273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media\/62329"}],"wp:attachment":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media?parent=62261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/categories?post=62261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/tags?post=62261"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/yst_prominent_words?post=62261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}