{"id":61789,"date":"2019-10-06T10:49:35","date_gmt":"2019-10-06T14:49:35","guid":{"rendered":"https:\/\/www.ludwig-van.com\/montreal\/?p=61789"},"modified":"2019-10-07T19:45:12","modified_gmt":"2019-10-07T23:45:12","slug":"critique-marie-nicole-lemieux-baudelaire","status":"publish","type":"post","link":"https:\/\/www.ludwig-van.com\/montreal\/2019\/10\/06\/critique-marie-nicole-lemieux-baudelaire\/","title":{"rendered":"CRITIQUE | Marie-Nicole Lemieux : un magnifique hommage \u00e0 Baudelaire et \u00e0 la beaut\u00e9 de la po\u00e9sie"},"content":{"rendered":"<figure id=\"attachment_61790\" aria-describedby=\"caption-attachment-61790\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-61790\" src=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/Marie-Nicole-Lemieux-critique-SIX-M\u00c9DIAS.jpg\" alt=\"Marie-Nicole Lemieux\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/Marie-Nicole-Lemieux-critique-SIX-M\u00c9DIAS.jpg 1200w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/Marie-Nicole-Lemieux-critique-SIX-M\u00c9DIAS-300x157.jpg 300w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/Marie-Nicole-Lemieux-critique-SIX-M\u00c9DIAS-768x402.jpg 768w, https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/Marie-Nicole-Lemieux-critique-SIX-M\u00c9DIAS-1024x536.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-61790\" class=\"wp-caption-text\">Marie-Nicole Lemieux pr\u00e9sente sa tourn\u00e9e \u00ab\u00a0Invitation au voyage\u00a0\u00bb dans plusieurs villes du Qu\u00e9bec cet automne. (Photo: courtoisie de Six M\u00e9dias)<\/figcaption><\/figure>\n<p>Cette semaine, <strong>Marie-Nicole Lemieux<\/strong> lan\u00e7ait sa tourn\u00e9e de 10 villes du Qu\u00e9bec \u00e0 la salle Bourgie. Le spectacle <strong><em>L&rsquo;Invitation au voyage<\/em><\/strong>, avec <strong>Raymond Cloutier<\/strong> et le pianiste <strong>Daniel Blumenthal<\/strong>, est une proposition bien con\u00e7ue, \u00e9l\u00e9gante, agr\u00e9able, sans artifices et bref, tr\u00e8s r\u00e9ussie. <strong>Critique.\u00a0<\/strong><\/p>\n<p>Sans doute par ins\u00e9curit\u00e9, il arrive parfois que les artistes en fassent trop. On croit souvent qu&rsquo;il est n\u00e9cessaire d&rsquo;ajouter mille gadgets pour \u00e9pater la galerie, en s&rsquo;imaginant, \u00e0 tort, que le spectateur moderne est trop distrait pour se concentrer sur la musique. Or, cela produit souvent l&rsquo;effet contraire \u00e0 celui que l&rsquo;on aurait souhait\u00e9 en diluant l&rsquo;essentiel. Les artistes de la trempe de <strong>Marie-Nicole Lemieux<\/strong> et <strong>Raymond Cloutier<\/strong> n&rsquo;ont pas ce probl\u00e8me, c&rsquo;est pourquoi la simplicit\u00e9 de la mise en sc\u00e8ne de <strong><em>L&rsquo;Invitation au voyage<\/em><\/strong> contribue \u00e0 nous faire appr\u00e9cier ce qu&rsquo;ils ont de plus important \u00e0 nous offrir: leur immense talent.<\/p>\n<p>Un d\u00e9cor simple mais chaleureux, constitu\u00e9 de quelques meubles d&rsquo;\u00e9poque de part et d&rsquo;autre du piano suffit \u00e0 cr\u00e9er une ambiance intimiste propice \u00e0 la po\u00e9sie. Sur grand \u00e9cran, on projette des images reli\u00e9es aux pi\u00e8ces que l&rsquo;on entend: tableaux, photos, pages de livres et bien s\u00fbr la couverture des <em>Fleurs du mal<\/em>, de <strong>Charles Baudelaire<\/strong>, po\u00e8te au centre de ce \u00ab\u00a0voyage\u00a0\u00bb musico-th\u00e9\u00e2tral. Il n&rsquo;en faut pas plus. On fait confiance au spectateur. Nous n&rsquo;avons pas besoin d&rsquo;effets sp\u00e9ciaux pour appr\u00e9cier le chant sublime de notre contralto nationale et le th\u00e9\u00e2tre authentique et sinc\u00e8re de son complice, <b>Raymond Cloutier<\/b>, sans oublier les magnifiques couleurs que <strong>Daniel Blumenthal<\/strong> fait entendre au piano.<\/p>\n<p>Le tout commence avec <em>L&rsquo;Albatros<\/em>, que <strong>Raymond Cloutier, <\/strong>qui incarne <strong>Charles Baudelaire,<\/strong> d\u00e9clame en s&rsquo;adressant \u00e0 nous comme un vrai personnage de th\u00e9\u00e2tre et non comme un \u00ab\u00a0lecteur\u00a0\u00bb de po\u00e9sie qui r\u00e9cite sur un ton solennel, comme c&rsquo;est souvent le cas dans ce genre de spectacles avec musique et textes. La diff\u00e9rence, essentielle, r\u00e9side dans le fait qu&rsquo;un r\u00e9citant dot\u00e9 d&rsquo;une bonne diction peut certes faire passer un texte, mais un v\u00e9ritable acteur peut le vivre et nous donner l&rsquo;impression d&rsquo;\u00eatre avec lui, comme si Baudelaire lui-m\u00eame nous parlait, sur le ton d&rsquo;une conversation normale.<\/p>\n<p>Les textes sont bien choisis pour renforcer cette impression, comme <em>\u00c0 une heure du matin<\/em>, extrait non pas des <strong><em>Fleurs du mal<\/em><\/strong>, mais du <strong><em>Spleen de Paris<\/em><\/strong>, un recueil posthume de po\u00e8mes en prose, dont le passage livr\u00e9 par <strong>Raymond Cloutier<\/strong> ressemble plut\u00f4t \u00e0 un journal, alors que <strong>Charles Baudelaire<\/strong> couche sur papier ses impressions de la ville et de la vie.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00ab\u00a0Enfin ! seul ! On n\u2019entend plus que le roulement de quelques fiacres attard\u00e9s et \u00e9reint\u00e9s. Pendant quelques heures, nous poss\u00e9derons le silence, sinon le repos. Enfin ! la tyrannie de la face humaine a disparu, et je ne souffrirai plus que par moi-m\u00eame.<br \/>\nEnfin ! il m\u2019est donc permis de me d\u00e9lasser dans un bain de t\u00e9n\u00e8bres ! D\u2019abord, un double tour \u00e0 la serrure. Il me semble que ce tour de clef augmentera ma solitude et fortifiera les barricades qui me s\u00e9parent actuellement du monde.\u00a0\u00bb &#8211; Charles Baudelaire, <em>\u00c0 une heure du matin<\/em>, <em>Le Spleen de Paris (1869)<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Les po\u00e8mes choisis et leur version sous forme de m\u00e9lodie par Ernest Chausson, Gabriel Faur\u00e9, Henri Duparc, forment un programme dont l&rsquo;esth\u00e9tique nous plonge dans une autre \u00e9poque. Ce soir-l\u00e0, en \u00e9coutant <strong>Marie-Nicole Lemieux <\/strong>chanter, des souvenirs surgissent et je r\u00e9alise quatre choses: d&rsquo;abord, qu&rsquo;elle est la chanteuse lyrique qu\u00e9b\u00e9coise que j&rsquo;ai entendue le plus souvent en r\u00e9cital ou \u00e0 l&rsquo;op\u00e9ra; ensuite, que je me souviens clairement de toutes ces prestations, troisi\u00e8mement, qu&rsquo;elle est la seule chanteuse \u00e0 m&rsquo;avoir fait pleurer et finalement, qu&rsquo;elle continue encore d&rsquo;am\u00e9liorer son art et sa voix.<\/p>\n<p>S&rsquo;il est vrai que les r\u00f4les op\u00e9ratiques nous permettent d&rsquo;appr\u00e9cier \u00e9galement ses talents pour le jeu th\u00e9\u00e2tral, cet art raffin\u00e9 de la m\u00e9lodie nous fait d\u00e9couvrir la dimension plus subtile de ses qualit\u00e9s d&rsquo;interpr\u00e8te hors pair. On appr\u00e9cie aussi, dans sa voix, de nouvelles couleurs et des nuances toujours plus fines et plus riches, le r\u00e9sultat d&rsquo;ann\u00e9es de recherche et d&rsquo;efforts pour transmettre un texte avec du sens et de l&rsquo;intention musicale dans chaque phrase, un chant au service des oeuvres, \u00e0 l&rsquo;oppos\u00e9 d&rsquo;un chant qui se complait en lui-m\u00eame. Au piano, le fantastique <strong>Daniel Blumenthal<\/strong> n&rsquo;est pas qu&rsquo;un simple accompagnateur, mais bien un \u00e9l\u00e9ment indispensable de ce trio qui injecte une part suppl\u00e9mentaire de vie, de fluidit\u00e9 et de dynamisme au r\u00e9cital.<\/p>\n<p>Pour conclure, cette <strong><em>Invitation au voyage<\/em><\/strong> est une exp\u00e9rience infiniment satisfaisante pour ceux qui aiment la voix humaine, la musique, le piano la po\u00e9sie, le th\u00e9\u00e2tre, en fin de compte, tous ceux qui ont besoin de moments de beaut\u00e9 pour donner un sens \u00e0 la vie dans ce monde de fou.<\/p>\n<p>Vous voulez y aller?<strong> L&rsquo;Invitation au voyage<\/strong> avec <strong>Marie-Nicole Lemieux<\/strong>, <strong>Raymond Cloutier<\/strong> et <strong>Daniel Blumenthal<\/strong> sera \u00e9galement pr\u00e9sent\u00e9 dans d&rsquo;autres villes du Qu\u00e9bec gr\u00e2ce \u00e0 une tourn\u00e9e organis\u00e9e par l&rsquo;<strong>Agence Station Bleue. \u00a0<\/strong><\/p>\n<h2>HORAIRE DE LA TOURN\u00c9E DE MARIE-NICOLE LEMIEUX<\/h2>\n<p><a href=\"https:\/\/diffusionscoulisse.ca\/spectacles\/marie-nicole-lemieux\/\" target=\"_blank\" rel=\"noopener\">Beloeil, 6 octobre, 15 h, Centre culturel de Beloeil<\/a><\/p>\n<p><a href=\"https:\/\/www.clubmusicaldequebec.com\/cmq\/index.php\/programmation\/saison-2019-2020\/l-invitation-au-voyage-de-marie-nicole-lemieux\" target=\"_blank\" rel=\"noopener\">Qu\u00e9bec (COMPLET): 7 octobre, Club musical de Qu\u00e9bec, 20 h, Palais Montcalm<\/a><\/p>\n<p><a href=\"https:\/\/www.spectart.com\/programmation\/detail.php?di=1474&amp;sid=3&amp;dis=3\" target=\"_blank\" rel=\"noopener\">Rimouski, 9 octobre, 20 h, salle Desjardins-Telus<\/a><\/p>\n<p><a href=\"https:\/\/theatregillesvigneault.tuxedobillet.com\/main\/marie-nicole-lemieux\" target=\"_blank\" rel=\"noopener\">Saint-J\u00e9r\u00f4me, 11 octobre, 20 h, Th\u00e9\u00e2tre Gilles-Vigneault<\/a><\/p>\n<p><a href=\"https:\/\/spec.qc.ca\/spectacle\/marie-nicole-lemieux-et-raymond-cloutier\" target=\"_blank\" rel=\"noopener\">Saint-Jean-sur-Richelieu, 13 octobre, 15 h 30, Th\u00e9\u00e2tre des Deux-Rives<\/a><\/p>\n<p><a href=\"https:\/\/www.lecarre150.com\/spectacle\/detail\/Marie-Nicole-Lemieux-\/Linvitation-au-voyage--Baudelaire-en-paroles\/16-10-2019-20-00\" target=\"_blank\" rel=\"noopener\">Victoriaville, 16 octobre, 20 h, salle Les-Fr\u00e8res-Lemaire<\/a><\/p>\n<p><a href=\"https:\/\/www.theatredelaville.qc.ca\/programmation\/marie-nicole-lemieux\/\" target=\"_blank\" rel=\"noopener\">Longueuil, 17 octobre, 20 h, salle Pratt-and-Whitney Canada<\/a><\/p>\n<p><a href=\"http:\/\/www.orford.mu\/concerts-et-evenements\/marie-nicole-lemieux-linvitation-au-voyage\/\" target=\"_blank\" rel=\"noopener\">Orford, 18 octobre, 20 h, salle Gilles-Lefebvre<\/a><\/p>\n<p><a href=\"https:\/\/www.ovation.qc.ca\/Billets\/ChoixSpecDate.asp?CodeSalleSpectacle=2301F2&amp;CodeRepresentation=2303IF&amp;CodeSiteClient=000012&amp;Lang=FR\" target=\"_blank\" rel=\"noopener\">Terrebonne, 20 octobre, 20 h, Th\u00e9\u00e2tre du Vieux-Terrebonne<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>LIRE AUSSI:<\/h2>\n<blockquote class=\"wp-embedded-content\" data-secret=\"1SiDBG8Ip8\"><p><a href=\"https:\/\/www.ludwig-van.com\/montreal\/2019\/10\/03\/rencontre-mado-lamotte-pourquoi-jaime-lopera\/\">RENCONTRE | Mado Lamotte : \u00ab\u00a0Pourquoi j&rsquo;aime l&rsquo;op\u00e9ra\u00a0\u00bb<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.ludwig-van.com\/montreal\/2019\/10\/03\/rencontre-mado-lamotte-pourquoi-jaime-lopera\/embed\/#?secret=1SiDBG8Ip8\" data-secret=\"1SiDBG8Ip8\" width=\"600\" height=\"338\" title=\"\u00ab\u00a0RENCONTRE | Mado Lamotte : \u00ab\u00a0Pourquoi j&rsquo;aime l&rsquo;op\u00e9ra\u00a0\u00bb\u00a0\u00bb &#8212; Ludwig Van Montreal\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette semaine, Marie-Nicole Lemieux lan\u00e7ait sa tourn\u00e9e de 10 villes du Qu\u00e9bec \u00e0 la salle Bourgie. Le spectacle L&rsquo;Invitation au voyage, avec Raymond Cloutier et le pianiste Daniel Blumenthal, est une proposition bien con\u00e7ue, \u00e9l\u00e9gante, agr\u00e9able, sans artifices et bref, tr\u00e8s r\u00e9ussie. Critique. <\/p>\n","protected":false},"author":51,"featured_media":61790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jetpack_post_was_ever_published":false},"categories":[28802,52],"tags":[28789,31125,11138,11137],"yst_prominent_words":[15751,10159,15692,34963,27260,25535,10262,34959,34957,9886,11219,34960,26703,11699,11695,34961,34962,31123,34676,33505],"acf":[],"jetpack_featured_media_url":"https:\/\/www.ludwig-van.com\/montreal\/wp-content\/uploads\/sites\/3\/2019\/10\/Marie-Nicole-Lemieux-critique-SIX-M\u00c9DIAS.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9bdYt-g4B","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/61789"}],"collection":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/comments?post=61789"}],"version-history":[{"count":6,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/61789\/revisions"}],"predecessor-version":[{"id":61916,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/posts\/61789\/revisions\/61916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media\/61790"}],"wp:attachment":[{"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/media?parent=61789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/categories?post=61789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/tags?post=61789"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.ludwig-van.com\/montreal\/wp-json\/wp\/v2\/yst_prominent_words?post=61789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}